{"id":8929,"date":"2025-10-22T15:02:11","date_gmt":"2025-10-22T07:02:11","guid":{"rendered":"https:\/\/oydisplay.com\/?post_type=design&#038;p=8929"},"modified":"2025-10-22T15:02:14","modified_gmt":"2025-10-22T07:02:14","slug":"menswear-shop-interior-design","status":"publish","type":"design","link":"https:\/\/oydisplay.com\/ja\/design\/menswear-shop-interior-design\/","title":{"rendered":"\u30e1\u30f3\u30ba\u30a6\u30a7\u30a2\u30b7\u30e7\u30c3\u30d7\u5185\u88c5\u30c7\u30b6\u30a4\u30f3"},"content":{"rendered":"","protected":false},"featured_media":8935,"template":"","meta":{"_acf_changed":true},"design-category":[65,79],"class_list":["post-8929","design","type-design","status-publish","has-post-thumbnail","hentry","design-category-clothing-shop-design","design-category-menswear-store-design"],"acf":[],"_links":{"self":[{"href":"https:\/\/oydisplay.com\/ja\/wp-json\/wp\/v2\/design\/8929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oydisplay.com\/ja\/wp-json\/wp\/v2\/design"}],"about":[{"href":"https:\/\/oydisplay.com\/ja\/wp-json\/wp\/v2\/types\/design"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oydisplay.com\/ja\/wp-json\/wp\/v2\/media\/8935"}],"wp:attachment":[{"href":"https:\/\/oydisplay.com\/ja\/wp-json\/wp\/v2\/media?parent=8929"}],"wp:term":[{"taxonomy":"design-category","embeddable":true,"href":"https:\/\/oydisplay.com\/ja\/wp-json\/wp\/v2\/design-category?post=8929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}