{"id":5464,"date":"2025-07-30T16:10:10","date_gmt":"2025-07-30T08:10:10","guid":{"rendered":"https:\/\/oydisplay.com\/?post_type=design&#038;p=5464"},"modified":"2025-07-30T16:10:11","modified_gmt":"2025-07-30T08:10:11","slug":"jewellery-shop-modern-counter-ideas","status":"publish","type":"design","link":"https:\/\/oydisplay.com\/es\/design\/jewellery-shop-modern-counter-ideas\/","title":{"rendered":"Ideas modernas para mostradores en tiendas de joyer\u00eda"},"content":{"rendered":"","protected":false},"featured_media":5471,"template":"","meta":{"_acf_changed":true},"design-category":[59],"class_list":["post-5464","design","type-design","status-publish","has-post-thumbnail","hentry","design-category-jewelry-store-interior-design"],"acf":[],"_links":{"self":[{"href":"https:\/\/oydisplay.com\/es\/wp-json\/wp\/v2\/design\/5464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oydisplay.com\/es\/wp-json\/wp\/v2\/design"}],"about":[{"href":"https:\/\/oydisplay.com\/es\/wp-json\/wp\/v2\/types\/design"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oydisplay.com\/es\/wp-json\/wp\/v2\/media\/5471"}],"wp:attachment":[{"href":"https:\/\/oydisplay.com\/es\/wp-json\/wp\/v2\/media?parent=5464"}],"wp:term":[{"taxonomy":"design-category","embeddable":true,"href":"https:\/\/oydisplay.com\/es\/wp-json\/wp\/v2\/design-category?post=5464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}