{"id":5215,"date":"2025-07-28T13:38:31","date_gmt":"2025-07-28T05:38:31","guid":{"rendered":"https:\/\/oydisplay.com\/?post_type=design&#038;p=5215"},"modified":"2025-07-28T13:38:32","modified_gmt":"2025-07-28T05:38:32","slug":"diamond-store-reception-custom-ideas","status":"publish","type":"design","link":"https:\/\/oydisplay.com\/de\/design\/diamond-store-reception-custom-ideas\/","title":{"rendered":"Diamond Store Empfangsbereich Individuelle Ideen"},"content":{"rendered":"","protected":false},"featured_media":5223,"template":"","meta":{"_acf_changed":true},"design-category":[59],"class_list":["post-5215","design","type-design","status-publish","has-post-thumbnail","hentry","design-category-jewelry-store-interior-design"],"acf":[],"_links":{"self":[{"href":"https:\/\/oydisplay.com\/de\/wp-json\/wp\/v2\/design\/5215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oydisplay.com\/de\/wp-json\/wp\/v2\/design"}],"about":[{"href":"https:\/\/oydisplay.com\/de\/wp-json\/wp\/v2\/types\/design"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oydisplay.com\/de\/wp-json\/wp\/v2\/media\/5223"}],"wp:attachment":[{"href":"https:\/\/oydisplay.com\/de\/wp-json\/wp\/v2\/media?parent=5215"}],"wp:term":[{"taxonomy":"design-category","embeddable":true,"href":"https:\/\/oydisplay.com\/de\/wp-json\/wp\/v2\/design-category?post=5215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}