{"id":8929,"date":"2025-10-22T15:02:11","date_gmt":"2025-10-22T07:02:11","guid":{"rendered":"https:\/\/oydisplay.com\/?post_type=design&#038;p=8929"},"modified":"2025-10-22T15:02:14","modified_gmt":"2025-10-22T07:02:14","slug":"menswear-shop-interior-design","status":"publish","type":"design","link":"https:\/\/oydisplay.com\/ar\/design\/menswear-shop-interior-design\/","title":{"rendered":"\u062a\u0635\u0645\u064a\u0645 \u062f\u0627\u062e\u0644\u064a \u0644\u0645\u062a\u062c\u0631 \u0645\u0644\u0627\u0628\u0633 \u0631\u062c\u0627\u0644\u064a\u0629"},"content":{"rendered":"","protected":false},"featured_media":8935,"template":"","meta":{"_acf_changed":true},"design-category":[65,79],"class_list":["post-8929","design","type-design","status-publish","has-post-thumbnail","hentry","design-category-clothing-shop-design","design-category-menswear-store-design"],"acf":[],"_links":{"self":[{"href":"https:\/\/oydisplay.com\/ar\/wp-json\/wp\/v2\/design\/8929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oydisplay.com\/ar\/wp-json\/wp\/v2\/design"}],"about":[{"href":"https:\/\/oydisplay.com\/ar\/wp-json\/wp\/v2\/types\/design"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oydisplay.com\/ar\/wp-json\/wp\/v2\/media\/8935"}],"wp:attachment":[{"href":"https:\/\/oydisplay.com\/ar\/wp-json\/wp\/v2\/media?parent=8929"}],"wp:term":[{"taxonomy":"design-category","embeddable":true,"href":"https:\/\/oydisplay.com\/ar\/wp-json\/wp\/v2\/design-category?post=8929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}